{"id":570,"date":"2021-04-04T16:58:54","date_gmt":"2021-04-04T14:58:54","guid":{"rendered":"https:\/\/www.dominiquevanosch.nl\/?p=570"},"modified":"2021-04-04T17:00:19","modified_gmt":"2021-04-04T15:00:19","slug":"gazing-leopard","status":"publish","type":"post","link":"https:\/\/www.dominiquevanosch.nl\/en\/2021\/04\/04\/gazing-leopard\/","title":{"rendered":"Gazing leopard"},"content":{"rendered":"<p><\/p>\n\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>100 x 80 cm Oil painting on a linen cloth<\/p>","protected":false},"author":1,"featured_media":566,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[],"class_list":["post-570","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dieren"],"views":788,"_links":{"self":[{"href":"https:\/\/www.dominiquevanosch.nl\/en\/wp-json\/wp\/v2\/posts\/570","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dominiquevanosch.nl\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dominiquevanosch.nl\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dominiquevanosch.nl\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dominiquevanosch.nl\/en\/wp-json\/wp\/v2\/comments?post=570"}],"version-history":[{"count":3,"href":"https:\/\/www.dominiquevanosch.nl\/en\/wp-json\/wp\/v2\/posts\/570\/revisions"}],"predecessor-version":[{"id":573,"href":"https:\/\/www.dominiquevanosch.nl\/en\/wp-json\/wp\/v2\/posts\/570\/revisions\/573"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dominiquevanosch.nl\/en\/wp-json\/wp\/v2\/media\/566"}],"wp:attachment":[{"href":"https:\/\/www.dominiquevanosch.nl\/en\/wp-json\/wp\/v2\/media?parent=570"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dominiquevanosch.nl\/en\/wp-json\/wp\/v2\/categories?post=570"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dominiquevanosch.nl\/en\/wp-json\/wp\/v2\/tags?post=570"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}