{"id":186,"date":"2020-04-01T13:54:56","date_gmt":"2020-04-01T11:54:56","guid":{"rendered":"https:\/\/www.dominiquevanosch.nl\/?p=186"},"modified":"2020-04-24T09:27:24","modified_gmt":"2020-04-24T07:27:24","slug":"elisabeth","status":"publish","type":"post","link":"https:\/\/www.dominiquevanosch.nl\/en\/2020\/04\/01\/elisabeth\/","title":{"rendered":"Elisabeth"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>60 x 60 cm<br \/>\nOlieverf schilderij van mijn moeder.<\/p>","protected":false},"author":1,"featured_media":187,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"class_list":["post-186","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-portretten"],"views":837,"_links":{"self":[{"href":"https:\/\/www.dominiquevanosch.nl\/en\/wp-json\/wp\/v2\/posts\/186","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dominiquevanosch.nl\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dominiquevanosch.nl\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dominiquevanosch.nl\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dominiquevanosch.nl\/en\/wp-json\/wp\/v2\/comments?post=186"}],"version-history":[{"count":5,"href":"https:\/\/www.dominiquevanosch.nl\/en\/wp-json\/wp\/v2\/posts\/186\/revisions"}],"predecessor-version":[{"id":406,"href":"https:\/\/www.dominiquevanosch.nl\/en\/wp-json\/wp\/v2\/posts\/186\/revisions\/406"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dominiquevanosch.nl\/en\/wp-json\/wp\/v2\/media\/187"}],"wp:attachment":[{"href":"https:\/\/www.dominiquevanosch.nl\/en\/wp-json\/wp\/v2\/media?parent=186"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dominiquevanosch.nl\/en\/wp-json\/wp\/v2\/categories?post=186"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dominiquevanosch.nl\/en\/wp-json\/wp\/v2\/tags?post=186"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}